{"id":8313,"date":"2019-12-05T14:06:19","date_gmt":"2019-12-05T19:06:19","guid":{"rendered":"http:\/\/www.optionsfinancieres.com\/?p=8313"},"modified":"2020-12-18T14:07:42","modified_gmt":"2020-12-18T19:07:42","slug":"comment-faire-un-don-dune-police-dassurance-vie","status":"publish","type":"post","link":"https:\/\/www.optionsfinancieres.com\/fr\/comment-faire-un-don-dune-police-dassurance-vie\/","title":{"rendered":"Comment faire un don d&rsquo;une police d&rsquo;assurance-vie"},"content":{"rendered":"[vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb column_margin=\u00a0\u00bbdefault\u00a0\u00bb column_direction=\u00a0\u00bbdefault\u00a0\u00bb column_direction_tablet=\u00a0\u00bbdefault\u00a0\u00bb column_direction_phone=\u00a0\u00bbdefault\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb row_border_radius=\u00a0\u00bbnone\u00a0\u00bb row_border_radius_applies=\u00a0\u00bbbg\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_tablet=\u00a0\u00bbinherit\u00a0\u00bb column_padding_phone=\u00a0\u00bbinherit\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb column_link_target=\u00a0\u00bb_self\u00a0\u00bb gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb phone_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb column_border_width=\u00a0\u00bbnone\u00a0\u00bb column_border_style=\u00a0\u00bbsolid\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column_text]Votre situation a chang\u00e9 et vous n&rsquo;avez plus besoin de votre police d&rsquo;assurance-vie personnelle ou corporative?<\/p>\n<p>Faire un don de votre police d&rsquo;assurance-vie \u00e0 un organisme de bienfaisance pourrait \u00eatre bien plus avantageux pour vous que de la laisser tomber.<\/p>\n<p>Le don d&rsquo;une police d&rsquo;assurance-vie peut engendrer des \u00e9conomies d&rsquo;imp\u00f4ts importantes de votre vivant ou \u00e0 votre d\u00e9c\u00e8s tout en aidant un organisme qui vous tient \u00e0 c\u0153ur.<\/p>\n<p>Voici 2 mani\u00e8res de faire un don d&rsquo;une assurance-vie existante directement \u00e0 un organisme de bienfaisance, via la d\u00e9signation de b\u00e9n\u00e9ficiaire du contrat.<\/p>\n<p>La premi\u00e8re fa\u00e7on consiste simplement \u00e0 nommer un ou plusieurs organismes de bienfaisance accr\u00e9dit\u00e9(s) de votre choix \u00e0 titre de b\u00e9n\u00e9ficiaire de votre police d&rsquo;assurance-vie. \u00c0 votre d\u00e9c\u00e8s, l&rsquo;organisme en question recevra directement le montant d&rsquo;assurance et votre succession pourra r\u00e9clamer le cr\u00e9dit pour don de bienfaisance sur votre d\u00e9claration d&rsquo;imp\u00f4ts finale. Le cr\u00e9dit maximum pouvant \u00eatre r\u00e9clam\u00e9 est de 100% du revenu net de l&rsquo;assur\u00e9 pour l&rsquo;ann\u00e9e du d\u00e9c\u00e8s et l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. \u00c0 partir de 2016 des nouvelles r\u00e8gles fiscales permettront plus de souplesse concernant l&rsquo;application du cr\u00e9dit d&rsquo;imp\u00f4ts pour don de bienfaisance.<\/p>\n<p>Si c&rsquo;est une compagnie qui est propri\u00e9taire d&rsquo;une police d&rsquo;assurance-vie pour un actionnaire et le b\u00e9n\u00e9fici\u00e8re de la police est un organisme de bienfaisance alors la compagnie pourra b\u00e9n\u00e9ficier d&rsquo;une d\u00e9duction pour don de bienfaisance au d\u00e9c\u00e8s de l&rsquo;assur\u00e9.<\/p>\n<p>Puisque vous \u00eates toujours propri\u00e9taire de votre police d&rsquo;assurance, vous ne pouvez pas r\u00e9clamer le cr\u00e9dit d&rsquo;imp\u00f4t (d\u00e9duction si une compagnie) pour les primes d&rsquo;assurance pay\u00e9es de votre vivant ou pour les valeurs accumul\u00e9es, cependant vous gardez le contr\u00f4le et vous pouvez en tout temps changer de b\u00e9n\u00e9ficiaire ou d\u00e9cider de mettre fin a votre police et encaisser les valeurs de rachat s&rsquo;il y a lieu.<\/p>\n<p>La deuxi\u00e8me mani\u00e8re consiste \u00e0 c\u00e9der de fa\u00e7on permanente votre police d&rsquo;assurance-vie \u00e0 un organisme de bienfaisance accr\u00e9dit\u00e9, de cette mani\u00e8re l&rsquo;organisme en question deviendra \u00e0 la fois propri\u00e9taire et b\u00e9n\u00e9ficiaire de votre police d&rsquo;assurance-vie. Cette m\u00e9thode vous procure un avantage fiscal certain car les primes d&rsquo;assurance que vous pay\u00e9es et la valeur marchande de la police seront consid\u00e9r\u00e9es comme un don et vous donneront droit au cr\u00e9dit d&rsquo;imp\u00f4t pour don de bienfaisance. Si c&rsquo;est une compagnie qui c\u00e8de la police alors les primes pay\u00e9es et la valeur marchande de la police donneront droit \u00e0 une d\u00e9duction pour don de bienfaisance. \u00c0 votre d\u00e9c\u00e8s, l&rsquo;organisme recevra directement de la compagnie d&rsquo;assurance le montant du capital d\u00e9c\u00e8s \u00e0 titre de b\u00e9n\u00e9ficiaire de la police.<\/p>\n<p>Si vous cessez de payer les primes de la police qui a \u00e9t\u00e9 c\u00e9d\u00e9e \u00e0 un organisme, alors la police risque de tomber en d\u00e9ch\u00e9ance et l&rsquo;organisme pourra alors continuer de payer les primes ou mettre fin a la police et encaisser la valeur de rachat s&rsquo;il y a lieu.<\/p>\n<p>Si vous d\u00e9sirez r\u00e9server la possibilit\u00e9 de changer l&rsquo;organisme de bienfaisance qui b\u00e9n\u00e9ficiera de votre don ou si vous d\u00e9sirez an avoir plus qu&rsquo;un, alors vous pouvez choisir de faire le don de votre police \u00e0 une fondation communautaire qui offrira plus de souplesse quant au choix des b\u00e9n\u00e9ficiaires.<\/p>\n<p>La valeur marchande d&rsquo;une police d&rsquo;assurance-vie.<\/p>\n<p>Les autorit\u00e9s fiscales consid\u00e8rent que lorsqu&rsquo;une police d&rsquo;assurance-vie est c\u00e9d\u00e9e de fa\u00e7on permanente \u00e0 un organisme de bienfaisance, le donateur est r\u00e9put\u00e9 avoir fait un don \u00e9gal \u00e0 la juste valeur marchande de la police.<\/p>\n<p>La juste valeur marchande d&rsquo;une police d&rsquo;assurance-vie est d\u00e9termin\u00e9e par un calcul de plusieurs facteurs tels:<\/p>\n<ul>\n<li>La valeur de rachat<\/li>\n<li>Les pr\u00eats consentis \u00e0 partir de la valeur de rachat.<\/li>\n<li>L&rsquo;\u00e9tat de sant\u00e9 et l&rsquo;esp\u00e9rance de vie de l&rsquo;assur\u00e9.<\/li>\n<li>La valeur pr\u00e9sente des flux mon\u00e9taires estim\u00e9s.<\/li>\n<li>La valeur de remplacement.<\/li>\n<li>La possibilit\u00e9 de transformation.<\/li>\n<li>Les garantis compl\u00e9mentaires et autres modalit\u00e9s&#8230;.<\/li>\n<\/ul>\n<p>Il serait donc possible dans certaines circonstances qu&rsquo;une police d&rsquo;assurance-vie n&rsquo;ayant aucune valeur de rachat puisse tout de m\u00eame avoir une juste valeur marchande \u00e9lev\u00e9, par exemple: A cause de l&rsquo;\u00e9tat de sant\u00e9 et l&rsquo;esp\u00e9rance de vie de l&rsquo;assur\u00e9.<\/p>\n<p>L&rsquo;\u00e9valuation de la juste valeur marchande d&rsquo;une police doit \u00eatre calcul\u00e9e par un actuaire membre de la FICA (Fellow de l&rsquo;institut canadien des actuaires)<\/p>\n<p>La premi\u00e8re \u00e9tape consiste \u00e0 demander une \u00e9valuation pr\u00e9liminaire, afin de d\u00e9terminer si le gain fiscal d\u00e9coulant de la cession de la police pourra justifier le cout d&rsquo;obtenir une \u00e9valuation officielle de la juste valeur marchande de la police. A cette \u00e9tape, il faudra aussi d\u00e9terminer si le transfert d&rsquo;une police vers un organisme de bienfaisance va engendrer un gain sur police qui devra \u00eatre inclus dans le revenu du donateur. Il y a gain sur police lorsque la valeur de rachat net exc\u00e8de le cout de base rajust\u00e9 de la police.<\/p>\n<p>Votre don est important, car les coupures budg\u00e9taires des gouvernements am\u00e8ne les organismes de bienfaisance \u00e0 d\u00e9pendre de plus en plus des dons venant de citoyens et d&rsquo;entreprises. Si vous avez des questions \u00e0 ce sujet ou si vous \u00eates int\u00e9ress\u00e9 \u00e0 obtenir une \u00e9valuation pr\u00e9liminaire de votre police d&rsquo;assurance-vie, vous pouvez me contacter et il me fera plaisir de vous r\u00e9f\u00e9rer \u00e0 des experts en \u00e9valuation et vous aider \u00e0 compl\u00e9ter les questionnaires n\u00e9cessaires \u00e0 une \u00e9valuation de votre police d&rsquo;assurance.<\/p>\n<p>Steve Koncevich B.A.<br \/>\nConseiller en s\u00e9curit\u00e9 financi\u00e8re, Assureur-Vie Certifi\u00e9.<br \/>\nAcc\u00e8s Conseils Options Financi\u00e8res Inc.<br \/>\n514-231-0711[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb column_margin=\u00a0\u00bbdefault\u00a0\u00bb column_direction=\u00a0\u00bbdefault\u00a0\u00bb column_direction_tablet=\u00a0\u00bbdefault\u00a0\u00bb column_direction_phone=\u00a0\u00bbdefault\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb row_border_radius=\u00a0\u00bbnone\u00a0\u00bb row_border_radius_applies=\u00a0\u00bbbg\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_tablet=\u00a0\u00bbinherit\u00a0\u00bb column_padding_phone=\u00a0\u00bbinherit\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb column_link_target=\u00a0\u00bb_self\u00a0\u00bb gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[304],"tags":[],"class_list":{"0":"post-8313","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-articles"},"_links":{"self":[{"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/posts\/8313"}],"collection":[{"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/comments?post=8313"}],"version-history":[{"count":1,"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/posts\/8313\/revisions"}],"predecessor-version":[{"id":8315,"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/posts\/8313\/revisions\/8315"}],"wp:attachment":[{"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/media?parent=8313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/categories?post=8313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.optionsfinancieres.com\/fr\/wp-json\/wp\/v2\/tags?post=8313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}